{"id":26,"count":2,"description":"","link":"https:\/\/demos.codecaddies.co.za\/enegry\/category\/market\/","name":"Market","slug":"market","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demos.codecaddies.co.za\/enegry\/wp-json\/wp\/v2\/categories\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demos.codecaddies.co.za\/enegry\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demos.codecaddies.co.za\/enegry\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demos.codecaddies.co.za\/enegry\/wp-json\/wp\/v2\/posts?categories=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}